{"id":90915,"title":"Med Kanoon \u2013 Dulce tailand\u00e9s de jud\u00eda mungo","modified":"2026-07-21T13:18:00+02:00","plain":"\u00bfQu\u00e9 es el Med Kanoon?\n\n\n\nMe la juego publicando esto... porque si no consigo convencer a mis fieles lectores de esta delicia, nadie llegar\u00e1 a este art\u00edculo desde Google.\n\n\n\nSeg\u00fan mis pesquisas, nadie busca esta palabra en Francia. ABSOLUTAMENTE NADIE. Aun as\u00ed, en cuanto lo prob\u00e9 en Tailandia, se convirti\u00f3 al instante en uno de mis postres favoritos. Como con los Moo Ping o el pad kra pao, me he propuesto la misi\u00f3n personal de popularizar este plato por estos lares.\n\n\n\n\n\n\n\nAut\u00e9nticas peque\u00f1as semillas de placer\n\n\n\nEl Med Kanoon es un delicioso postre originario de la cocina tailandesa. Este bocado se prepara con una sabrosa combinaci\u00f3n de jud\u00edas mungo amarillas (dal) finamente trituradas, huevos frescos, az\u00facar granulado y cremosa leche de coco.\n\n\n\nTambi\u00e9n se le conoce como \u201csemillas de jack\u201d (un \u00e1rbol que nuestros amigos de La Reuni\u00f3n conocen bien, #tijack) porque se moldean en peque\u00f1as c\u00e1psulas que recuerdan a semillas.\n\n\n\n\n\n\n\n\n\n\n\nAdem\u00e1s de ser apreciado por su sabor suculento, el Med Kanoon tambi\u00e9n se utiliza en rituales religiosos en Tailandia, especialmente durante las ceremonias del d\u00eda de Buda, en bodas o incluso en el Songkran, el A\u00f1o Nuevo tailand\u00e9s.\n\n\n\n\u00bfA qu\u00e9 sabe el Med Kanoon?\n\n\n\nEl Med Kanoon tiene un sabor suave y ligeramente dulce, con una textura cremosa y aterciopelada. Las jud\u00edas mungo amarillas finamente trituradas aportan al postre una textura levemente granulosa, mientras que la leche de coco le confiere una riqueza y una untuosidad divinas. El az\u00facar a\u00f1ade un toque dulce sutil, sin resultar empalagoso.\n\n\n\n\n\n\n\nLa mezcla de sabores es sutil y equilibrada, y crea una sensaci\u00f3n de dulzor y cremosidad en boca. Es un postre refrescante que puede disfrutarse en cualquier momento del a\u00f1o, ya sea como final de comida o como tentempi\u00e9 dulce.\n\n\n\n\n\n\n\nSi nunca has probado el Med Kanoon, su sabor \u00fanico y delicioso te va a sorprender. De verdad.\n\n\n\nLos ingredientes de los Med Kanoon\n\n\n\nEmpezamos por las jud\u00edas mungo amarillas, tambi\u00e9n conocidas como dal. Se encuentran en todas partes. Son las que se espolvorean sobre el arroz glutinoso con mango.\n\n\n\n\n\n\n\nA continuaci\u00f3n, leche de coco. Puedes usar cualquier tipo, pero yo prefiero la denominada \u201ccremosa\u201d; el resultado es mucho mejor.\n\n\n\nPor \u00faltimo, necesitar\u00e1s az\u00facar, agua y yemas de huevo. Nada del otro mundo.\n\n\n\n\n\n\tMed Kanoon tailandeses aut\u00e9nticos\n\t\t\n\t\t\t\n\t\n\t\t\t\n\t\n\t\t200 g de frijoles mungo pelados110 g de az\u00facar200 ml de leche de coco5 yemas de huevo batidasPara el alm\u00edbar300 ml de agua300 ml de az\u00facar (use el mismo volumen que de agua)\t\n\t\n\t\tRemoje los frijoles mungo en agua a temperatura ambiente durante seis horas (o toda la noche). Nota: no se trata de la cantidad de agua indicada en la lista de ingredientesEsc\u00farralos (r\u00e1pido, sin complicarse) y coc\u00ednelos al vapor durante 20 minutosD\u00e9jelos enfriar durante diez minutosCol\u00f3quelos en una licuadora con la leche de coco y el az\u00facarTriture hasta obtener una pasta homog\u00e9nea (consulte las notas)Vierta ahora la pasta en un wok antiadherente y cali\u00e9ntela a fuego medio, removiendo de forma continua durante 10 a 15 minutos, hasta que tenga textura de masa.Cuando tenga la textura adecuada, deje que se enfr\u00ede unos minutos.Tome una porci\u00f3n de pasta y ru\u00e9dela entre las manos hasta darle forma de frijol; repita hasta utilizar toda la pasta de frijol mungo.En un bol peque\u00f1o, vierta las yemas de huevo batidas sobre los Med Kanoon y deje que las absorban durante diez minutos; mu\u00e9valos con cuidado para asegurarse de que todos tengan, en alg\u00fan momento, buen contacto con las yemas.A fuego medio-alto, ponga un volumen igual de agua y de az\u00facar, lleve a ebullici\u00f3n y espere 5 minutos para que espese ligeramente. Incorpore los Med Kanoon de uno en uno y coc\u00ednelos durante 5 a 7 minutos.S\u00e1quelos del alm\u00edbar y disfr\u00fatelos.\t\n\t\n\t\t\nNo es imprescindible que quede totalmente lisa; depende de si prefiere algo de textura o no.\nServir a temperatura ambiente.\nPuede preparar la pasta con antelaci\u00f3n. Tras pasar por la nevera, cali\u00e9ntela unos segundos en el microondas para que vuelva a ser maleable.\n\n\t\n\t\n\t\tDessert, SnackTha\u00eflandaisedessert tha\u00ef, Haricots mungo, Med Kanoon","_links":{"self":[{"href":"https:\/\/marcwiner.com\/es\/wp-json\/wp\/v2\/posts\/90915","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/marcwiner.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/marcwiner.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/marcwiner.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/marcwiner.com\/es\/wp-json\/wp\/v2\/comments?post=90915"}],"version-history":[{"count":3,"href":"https:\/\/marcwiner.com\/es\/wp-json\/wp\/v2\/posts\/90915\/revisions"}],"predecessor-version":[{"id":126955,"href":"https:\/\/marcwiner.com\/es\/wp-json\/wp\/v2\/posts\/90915\/revisions\/126955"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/marcwiner.com\/es\/wp-json\/wp\/v2\/media\/8171"}],"wp:attachment":[{"href":"https:\/\/marcwiner.com\/es\/wp-json\/wp\/v2\/media?parent=90915"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/marcwiner.com\/es\/wp-json\/wp\/v2\/categories?post=90915"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/marcwiner.com\/es\/wp-json\/wp\/v2\/tags?post=90915"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}