{"id":156356,"title":"M\u1ebb aut\u00e9ntico \u2013 arroz fermentado vietnamita","modified":"2026-07-21T13:18:00+02:00","plain":"La fermentaci\u00f3n es, desde hace siglos, una t\u00e9cnica que permite conservar los alimentos y enriquecerlos desde el punto de vista nutricional, con especial protagonismo del arroz en Asia. En la cocina asi\u00e1tica, esta fermentaci\u00f3n del arroz ha dado lugar a numerosos platos deliciosos. \n\n\n\nPor ejemplo, entre los arroces fermentados podemos citar el koji de la cocina japonesa, el jiuniang o c\u01a1m r\u01b0\u1ee3u de la cocina china y vietnamita, el tapai de la cocina indonesia o incluso el vinagre de arroz. En Vietnam tambi\u00e9n existe una receta de arroz fermentado menos conocida, pero muy sabrosa: el m\u1ebb. \n\n\n\nEste condimento, acompa\u00f1ado adem\u00e1s de una receta (\u00a1si te atreves!), es tan poco conocido que, de hecho, apenas existe informaci\u00f3n en franc\u00e9s sobre este manjar. Encontr\u00e9 un peque\u00f1o hilo de discusi\u00f3n en un foro angl\u00f3fono, pero ah\u00ed terminaba todo&#8230; Fue gracias a una nueva integrante del equipo de la web, Loan, vietnamita, como supe de su existencia.\n\n\n\n\u00bfQu\u00e9 es el m\u1ebb ?\n\n\n\nM\u1ebb, c\u01a1m m\u1ebb o m\u1ebb chua son los nombres que recibe en Vietnam un tipo de arroz fermentado de sabor \u00e1cido. Es un condimento tradicional muy popular en el norte del pa\u00eds, su regi\u00f3n de origen, as\u00ed como en algunas zonas del centro y del sur.\n\n\n\nEl m\u1ebb es el resultado de la fermentaci\u00f3n l\u00e1ctica del arroz no glutinoso, lo que lo distingue de otros tipos de arroz fermentado como el koji y el jiuniang, que proceden de la llamada fermentaci\u00f3n alcoh\u00f3lica del arroz glutinoso. \n\n\n\nEl proceso de fermentaci\u00f3n favorece la aparici\u00f3n de levaduras, nematodos llamados Panagrellus redivivus (con m\u1ebb en vietnamita) y bacterias l\u00e1cticas, que transforman el az\u00facar del arroz en \u00e1cido l\u00e1ctico y crean as\u00ed el sabor y el aroma \u00e1cidos tan caracter\u00edsticos del m\u1ebb. Si quieres hacerte una idea m\u00e1s precisa de su sabor, recuerda un poco al nem chua.\n\n\n\nNem chua vietnamita\n\n\n\n\u00bfC\u00f3mo reconocer un m\u1ebb de buena calidad?\n\n\n\nEn Vietnam, se reconoce por los diminutos nematodos (gusanos blancos min\u00fasculos, peque\u00f1\u00ediiisimos, pero visibles a simple vista) que pululan por su superficie. Buen provecho.\n\n\n\nC\u00f3mo usar el m\u1ebb en la cocina\n\n\n\nEl m\u1ebb aporta su caracter\u00edstico toque \u00e1cido a muchos platos vietnamitas.\n\n\n\nEn sopas como las de fideos de arroz con cangrejo, pescado o caracoles (b\u00fan ri\u00eau), se pueden mezclar unas cucharadas de m\u1ebb con un peque\u00f1o cuenco de agua fr\u00eda y colar la mezcla para obtener el jugo de m\u1ebb, que luego se incorpora a las sopas.\n\n\n\nTambi\u00e9n es posible marinar ciertas carnes y pescados con m\u1ebb para atenuar su olor fuerte. Es el caso del pescado a la parrilla (ch\u1ea3 c\u00e1), una especialidad imprescindible de Han\u00f3i.\n\n\n\nAdem\u00e1s, los vietnamitas utilizan el m\u1ebb, mezclado con salsa de pescado y otros condimentos, para preparar nuoc cham y acompa\u00f1ar, por ejemplo, unos rollitos nem.\n\n\n\nCaracoles hervidos acompa\u00f1ados de una salsa elaborada con arroz fermentado m\u1ebb\n\n\n\n\u00bfC\u00f3mo conservar el m\u1ebb?\n\n\n\nPara conservar el m\u1ebb durante mucho tiempo, hay que respetar estas tres reglas:\n\n\n\n\nLos ingredientes utilizados para preparar este condimento no deben estar contaminados con bacterias nocivas, as\u00ed que conviene esterilizarlo todo muy bien.\n\n\n\nLos utensilios utilizados para producir, conservar y manipular el m\u1ebb deben estar limpios. Se recomienda esterilizarlos y secarlos antes de usarlos.\n\n\n\nLos nematodos deben alimentarse con regularidad. A\u00f1ade un peque\u00f1o cuenco de arroz al tarro una vez por semana.\n\n\n\n\nSi se conserva bien, el m\u1ebb puede seguir siendo comestible durante varios meses. Eso s\u00ed, si detectas la m\u00e1s m\u00ednima se\u00f1al de deterioro, como moho, hay que tirar el condimento de inmediato.\n\n\n\n\u00bfD\u00f3nde comprar m\u1ebb?\n\n\n\nNo es f\u00e1cil encontrar m\u1ebb fuera de Vietnam. Aun as\u00ed, en Europa se vende en algunas tiendas de alimentaci\u00f3n y establecimientos especializados en productos vietnamitas. Las marcas Ng\u1ecdc Li\u00ean y H\u01b0\u01a1ng Sen son las m\u00e1s conocidas.\n\n\n\n\u00bfC\u00f3mo sustituir el m\u1ebb?\n\n\n\nSi no consigues comprar m\u1ebb cerca de casa o no quieres prepararlo, puedes recurrir al lim\u00f3n, al vinagre de arroz, al tamarindo o al yogur natural sin az\u00facar para recuperar ese sabor \u00e1cido. Sin embargo, no obtendr\u00e1s el matiz tan espec\u00edfico de este condimento.\n\n\n\nBeneficios del m\u1ebb para la salud\n\n\n\nComo el yogur, el m\u1ebb es rico en \u00e1cidos l\u00e1cticos, vitaminas y prote\u00ednas que contribuyen a mejorar el sistema digestivo. As\u00ed, puede favorecer la digesti\u00f3n, aliviar ciertas molestias digestivas y estimular el apetito. \n\n\n\nAdem\u00e1s, puede combatir bacterias nocivas como E. coli y Salmonella, ayudando as\u00ed a proteger el tracto digestivo. \n\n\n\n\u00bfC\u00f3mo preparar m\u1ebb?\n\n\n\nExisten varias recetas para elaborar m\u1ebb. Aqu\u00ed tienes las dos m\u00e1s sencillas. Por desgracia, no hay cantidades exactas; futuras pruebas me permitir\u00e1n afinarlas:\n\n\n\n\n\n\tM\u1ebb aut\u00e9ntico, arroz fermentado vietnamita\n\t\t\n\t\t\t\n\t\n\t\tcuiseur \u00e0 riz\t\n\t\n\t\tM\u00e9todo tradicionalarroz no glutinosoagua para cocer el arrozagua para lavar el arrozun tarro de vidrio limpioM\u00e9todo r\u00e1pido1 bol de arroz no glutinoso muy cocido3 cucharadas agua tibia2.5 cucharaditas yogur natural sin az\u00facar, a temperatura ambienteun tarro de vidrio limpio\t\n\t\n\t\tM\u00e9todo tradicionalLava el arroz antes de cocerlo.Cuece el arroz en la arrocera con abundante agua durante bastante tiempo, hasta que quede muy blando.Hierve el agua con la que lavaste el arroz durante unos diez minutos.Vierte el agua hervida en el tarro de vidrio.Deja enfriar el arroz y el agua hervida hasta que alcancen la temperatura ambiente.Pon el arroz en el tarro y aseg\u00farate de que quede completamente sumergido en el agua.Cierra el tarro sin apretarlo demasiado.Coloca el tarro en un lugar seco, no necesariamente fresco, protegido de la luz.Espera entre 7 y 10 d\u00edas hasta que el m\u1ebb est\u00e9 listo.M\u00e9todo r\u00e1pidoVierte el agua tibia sobre el arroz muy cocido.Mezcla el arroz con el yogur.Pasa la mezcla a un tarro de vidrio limpio.Cierra el tarro herm\u00e9ticamente.Coloca el tarro en un bol con agua a 80 \u00b0C y d\u00e9jalo all\u00ed.Espera entre 2 y 3 d\u00edas hasta que el m\u1ebb est\u00e9 listo. Si usas un horno para mantener una temperatura constante de 80 grados, estar\u00e1 listo en 9 h.\t\n\t\n\t\tEl m\u1ebb debe tener un color blanco opaco.\nDebe tener un sabor \u00e1cido y una textura suave.\nSi el m\u1ebb tiene demasiada agua o desprende olor a alcohol, la preparaci\u00f3n no ha salido bien.\n\t\n\t\n\t\tVietnamienneriz ferment\u00e9","_links":{"self":[{"href":"https:\/\/marcwiner.com\/es\/wp-json\/wp\/v2\/posts\/156356","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/marcwiner.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/marcwiner.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/marcwiner.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/marcwiner.com\/es\/wp-json\/wp\/v2\/comments?post=156356"}],"version-history":[{"count":0,"href":"https:\/\/marcwiner.com\/es\/wp-json\/wp\/v2\/posts\/156356\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/marcwiner.com\/es\/wp-json\/wp\/v2\/media\/8719"}],"wp:attachment":[{"href":"https:\/\/marcwiner.com\/es\/wp-json\/wp\/v2\/media?parent=156356"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/marcwiner.com\/es\/wp-json\/wp\/v2\/categories?post=156356"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/marcwiner.com\/es\/wp-json\/wp\/v2\/tags?post=156356"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}